{"id":753,"date":"2024-04-19T18:33:50","date_gmt":"2024-04-19T18:33:50","guid":{"rendered":"https:\/\/bertolinidirect.com\/?page_id=753"},"modified":"2026-01-29T15:29:31","modified_gmt":"2026-01-29T15:29:31","slug":"faqs","status":"publish","type":"page","link":"https:\/\/bertolinidirect.com\/es\/faqs","title":{"rendered":"Preguntas frecuentes"},"content":{"rendered":"<h2 class=\"wp-block-heading\" id=\"h-general-questions\">Preguntas generales<\/h2>\n\n\n\n<div class=\"wp-block-bertolini-accordion mityinc-block\"><h3 class=\"header\">\u00bfD\u00f3nde se fabrican las sillas Bertolini?<\/h3><div class=\"body\">\n<p>Bertolini tiene su sede en Orem, Utah, EE. UU. y fabrica sillas para iglesias a medida en EE. UU. y en el extranjero. <a href=\"\/es\/products\/chairs\/impressions-chair\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Sillas Impresiones<\/strong><\/a> est\u00e1n dise\u00f1ados y fabricados en Utah, EE. UU. Bertolini <a href=\"\/es\/products\/chairs\/essentials-church-chair\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Sillas Essentials V2<\/strong><\/a> est\u00e1n dise\u00f1ados en los EE. UU. y fabricados en Asia.<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-bertolini-accordion mityinc-block\"><h3 class=\"header\">\u00bfQu\u00e9 pasa si el tiempo es un factor enorme?<\/h3><div class=\"body\">\n<p>La silla Bertolini Impressions se fabrica en EE. UU., lo que se traduce en una entrega m\u00e1s r\u00e1pida en comparaci\u00f3n con los modelos importados. Adem\u00e1s, disponemos de un amplio stock de sillas Essentials V2, de la serie HD y sillas plegables Brisa para cuando nuestros clientes necesitan soluciones de asientos r\u00e1pidas.<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-bertolini-accordion mityinc-block\"><h3 class=\"header\">\u00bfC\u00f3mo elijo la silla m\u00e1s c\u00f3moda?<\/h3><div class=\"body\">\n<p>La mejor manera de conseguir la silla de iglesia m\u00e1s c\u00f3moda es conseguir varias sillas de muestra y compararlas en persona, una al lado de la otra. Todas las sillas fabricadas por Bertolini est\u00e1n dise\u00f1adas pensando en la comodidad. Cada componente, desde la espuma hasta el marco, ha sido dise\u00f1ado para brindar una comodidad superior. Se garantiza que las sillas Bertolini mantendr\u00e1n su alto nivel de confort durante toda la vida \u00fatil de la silla.<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-bertolini-accordion mityinc-block\"><h3 class=\"header\">\u00bfQu\u00e9 pasa si tenemos almacenamiento limitado en mi iglesia?<\/h3><div class=\"body\">\n<p>Si dispone de espacio de almacenamiento limitado, las sillas Bertolini son perfectas para su iglesia. Todas nuestras sillas est\u00e1n dise\u00f1adas para ser ligeras, apilables y f\u00e1ciles de montar, mover y guardar. Cuentan con resistentes estructuras de acero. A diferencia de otros productos, las sillas Bertolini incorporan botones de apilamiento de alta calidad en el interior de las patas para facilitar y agilizar el apilamiento.<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-bertolini-accordion mityinc-block\"><h3 class=\"header\">\u00bfQu\u00e9 pasa si necesito sillas, pero tengo un presupuesto limitado?<\/h3><div class=\"body\">\n<p>En Bertolini, queremos facilitar a nuestros clientes la obtenci\u00f3n de los productos que necesitan. Trabajaremos con usted para encontrar productos que se ajusten a su presupuesto. Contamos con una amplia gama de soluciones de asientos para todos los presupuestos, desde la silla de iglesia Impressions, personalizable, hasta la econ\u00f3mica Essentials V2, pasando por las sillas apilables HD ultracompactas.<\/p>\n\n\n\n<p>A muchas iglesias les resulta conveniente comprar sillas en bloques. Queremos que compren las sillas a su propio ritmo y no sentir\u00e1n ninguna presi\u00f3n por nuestra parte. Bertolini tambi\u00e9n ofrece... <a href=\"https:\/\/bertolinidirect.com\/es\/blog\/how-to-host-a-fundraiser\/\">gu\u00eda gratuita para recaudar fondos<\/a> lo que ha ayudado a muchas iglesias a recaudar dinero para comprar sillas nuevas.<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-bertolini-accordion mityinc-block\"><h3 class=\"header\">\u00bfQu\u00e9 tan vers\u00e1tiles son las sillas de iglesia Bertolini?<\/h3><div class=\"body\">\n<p>Bertolini se dedica a la fabricaci\u00f3n de sillas vers\u00e1tiles que se adaptan a diversos espacios y situaciones. Nuestras sillas son ligeras y est\u00e1n dise\u00f1adas para apilarse o plegarse f\u00e1cilmente (seg\u00fan el modelo), lo que permite moverlas y guardarlas con facilidad en espacios reducidos. Adem\u00e1s, pueden unirse en filas y sustituir los bancos de iglesia como soluci\u00f3n de asientos permanente.<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-bertolini-accordion mityinc-block\"><h3 class=\"header\">\u00bfQu\u00e9 puedo esperar durante el proceso de compra una vez realizado mi pedido de sillas Bertolini?<\/h3><div class=\"body\">\n<ol class=\"wp-block-list\">\n<li>Recibir\u00e1s un recibo por correo electr\u00f3nico.<\/li>\n\n\n\n<li>Una vez fabricadas todas sus sillas, realizamos una rigurosa inspecci\u00f3n de control de calidad.<\/li>\n\n\n\n<li>Cuando el pedido est\u00e9 listo, recibir\u00e1 informaci\u00f3n de entrega, incluyendo la informaci\u00f3n de contacto del transportista, el n\u00famero de seguimiento y la fecha de entrega prevista.<\/li>\n\n\n\n<li>Su empresa de transporte se pondr\u00e1 en contacto con usted a m\u00e1s tardar 24 horas antes de la entrega para concertar una cita.<\/li>\n\n\n\n<li>Cuando lleguen las sillas, usted (y sus ayudantes) las descargar\u00e1n del cami\u00f3n (a menos que se hagan otros arreglos).<\/li>\n<\/ol>\n<\/div><\/div>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-frame-construction\">Construcci\u00f3n de marco<\/h2>\n\n\n\n<div class=\"wp-block-bertolini-accordion mityinc-block\"><h3 class=\"header\">\u00bfQu\u00e9 es un asiento FormFlex\u2122 y qu\u00e9 sillas lo tienen?<\/h3><div class=\"body\">\n<p>Nuestra base de asiento FormFlex patentada es una base de pl\u00e1stico moldeado que proporciona una base c\u00f3moda para la silla. La mayor\u00eda de las sillas de iglesia tienen una base de madera contrachapada debajo del coj\u00edn de espuma, que puede resultar firme e inc\u00f3moda despu\u00e9s de poco tiempo. El asiento FormFlex fue dise\u00f1ado espec\u00edficamente para mejorar la comodidad durante largos periodos de tiempo sentado. Esta base tiene la flexibilidad justa para evitar que la persona se hunda hasta el fondo del coj\u00edn, proporcionando as\u00ed un soporte superior y una comodidad inigualable. El asiento FormFlex est\u00e1 disponible en <a href=\"\/es\/products\/chairs\/impressions-chair\/\">Sillas Impresiones<\/a>.<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-bertolini-accordion mityinc-block\"><h3 class=\"header\">\u00bfQu\u00e9 tan bien se compara el asiento FormFlex\u2122 con los asientos fabricados por otros fabricantes de sillas para iglesias?<\/h3><div class=\"body\">\n<p>Disponible en la silla Impressions, la base de asiento FormFlex patentada ofrece mayor comodidad y durabilidad que otras sillas para iglesias. Esta base se flexiona al sentarse, adapt\u00e1ndose a la perfecci\u00f3n a cada persona. Adem\u00e1s, est\u00e1 fabricada en pl\u00e1stico moldeado, lo que la hace m\u00e1s ligera que las sillas con base de madera contrachapada. La base cuenta con un coj\u00edn de espuma de primera calidad, ultra c\u00f3modo, que durar\u00e1 m\u00e1s de 25 a\u00f1os.<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-bertolini-accordion mityinc-block\"><h3 class=\"header\">\u00bfC\u00f3mo funciona el recubrimiento en polvo y por qu\u00e9 es una caracter\u00edstica importante a buscar en las sillas?<\/h3><div class=\"body\">\n<p>Las sillas con estructura de acero con recubrimiento en polvo se encuentran entre las m\u00e1s duraderas, ecol\u00f3gicas y resistentes. Todas las sillas tapizadas Bertolini cuentan con acabados de recubrimiento en polvo. El proceso de recubrimiento comienza con un lavado \u00e1cido de la estructura para eliminar aceites y residuos de soldadura. A continuaci\u00f3n, la estructura se coloca en un bastidor y se introduce en una m\u00e1quina que magnetiza el metal y aplica la pintura mediante pulverizaci\u00f3n. Finalmente, la estructura se hornea para que el recubrimiento en polvo adquiera una capa dura. Este proceso se realiza en la planta de fabricaci\u00f3n de Bertolini para garantizar la m\u00e1xima calidad en cada etapa. Esto significa que el color de su estructura se mantendr\u00e1 intacto durante m\u00e1s tiempo, sin decolorarse ni agrietarse.<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-bertolini-accordion mityinc-block\"><h3 class=\"header\">\u00bfLos acabados con recubrimiento en polvo son ecol\u00f3gicos?<\/h3><div class=\"body\">\n<p>S\u00ed, nuestro m\u00e9todo de recubrimiento en polvo no genera emisiones y no contribuye a la contaminaci\u00f3n atmosf\u00e9rica. No utilizamos acabados electrochapados debido a la contaminaci\u00f3n t\u00f3xica que produce este proceso. En su lugar, utilizamos sistemas de recubrimiento en polvo aut\u00f3nomos. Nuestro sistema de recubrimiento en polvo de \u00faltima generaci\u00f3n y respetuoso con el medio ambiente garantiza que sus sillas tengan acabados de la m\u00e1s alta calidad con un impacto ambiental nulo.<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-bertolini-accordion mityinc-block\"><h3 class=\"header\">\u00bfPara qu\u00e9 sirve la barra de torsi\u00f3n?<\/h3><div class=\"body\">\n<p>En todas las sillas Bertolini Church Chairs, podr\u00e1 observar la barra de torsi\u00f3n soldada en la parte posterior del armaz\u00f3n, justo debajo del respaldo. Esta barra de acero refuerza nuestros armazones de calibre 16, aportando estabilidad, absorbiendo impactos y evitando que la silla se tuerza o se mueva. Adem\u00e1s, protege las juntas de soldadura durante el apilamiento y desapilamiento. La incorporaci\u00f3n de la barra de torsi\u00f3n, junto con una soldadura de alta calidad, da como resultado un armaz\u00f3n muy resistente.<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-bertolini-accordion mityinc-block\"><h3 class=\"header\">\u00bfQu\u00e9 es la flexi\u00f3n del mandril y cu\u00e1l es el beneficio de tener esta caracter\u00edstica en las sillas de la iglesia?<\/h3><div class=\"body\">\n<p>El acero utilizado para fabricar las sillas de iglesia Bertolini est\u00e1 doblado con mandril, lo que da como resultado una estructura m\u00e1s atractiva, segura y resistente. Muchos fabricantes de sillas de iglesia construyen sus marcos utilizando flexi\u00f3n por aplastamiento, una t\u00e9cnica que debilita el marco y deja una hendidura poco atractiva. Por el contrario, el doblado con mandril coloca un inserto (un mandril) en el tubo cuando se realiza el doblado para evitar el colapso. Si bien esto puede no ser tan r\u00e1pido o tan f\u00e1cil como doblar por aplastamiento, da como resultado una curvatura superior que mantiene la integridad total de la tuber\u00eda de acero. Esta es exactamente la raz\u00f3n por la que NASCAR exige que se utilice este tipo de curvatura para los tubos de las jaulas de seguridad de todos los coches de carreras.<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-bertolini-accordion mityinc-block\"><h3 class=\"header\">\u00bfPor qu\u00e9 es importante tener acero laminado en fr\u00edo en las sillas de la iglesia?<\/h3><div class=\"body\">\n<p>Comenzamos nuestro proceso de fabricaci\u00f3n de sillas utilizando tubos de acero laminado en fr\u00edo 1010 de alta calidad, soldados con precisi\u00f3n. El acero laminado en fr\u00edo es m\u00e1s resistente y tiene un acabado m\u00e1s liso que el acero laminado en caliente. B\u00e1sicamente, el acero laminado en fr\u00edo se somete a todo el proceso de laminado en caliente, adem\u00e1s de un proceso de laminado en fr\u00edo. Esto le confiere mayor resistencia y una superficie de calidad superior. El acero laminado en fr\u00edo es ideal para muebles porque, adem\u00e1s de ofrecer una textura lisa y sin imperfecciones, proporciona una superficie \u00f3ptima para la adherencia del recubrimiento en polvo.<\/p>\n<\/div><\/div>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-ratings-amp-tests\">Calificaciones y pruebas<\/h2>\n\n\n\n<div class=\"wp-block-bertolini-accordion mityinc-block\"><h3 class=\"header\">\u00bfQu\u00e9 tipo de pruebas de control de calidad realiza Bertolini a las sillas?<\/h3><div class=\"body\">\n<p>Si necesita sillas duraderas que puedan soportar un uso intenso y un peso elevado, necesita las sillas Bertolini. Antes de envolver el pedido de cualquier cliente para su env\u00edo, todas las sillas deben pasar una rigurosa inspecci\u00f3n de control de calidad que cumpla con la norma ISO 9000. Nuestros inspectores miden 8 puntos de inspecci\u00f3n en todas nuestras sillas de iglesia. Las sillas que no cumplen con los est\u00e1ndares son rechazadas y reemplazadas antes de enviar su pedido.<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-bertolini-accordion mityinc-block\"><h3 class=\"header\">\u00bfQu\u00e9 es la prueba de carga est\u00e1tica enfocada y por qu\u00e9 es importante?<\/h3><div class=\"body\">\n<p>Durante la prueba de carga est\u00e1tica, se colocan 800 libras de peso concentrado en el centro de la base del asiento. Durante las pruebas, todos los asientos de las sillas Bertolini resistieron f\u00e1cilmente la carga concentrada. Realizamos estas pruebas peri\u00f3dicamente para asegurar la calidad y durabilidad de las sillas. Esto le dar\u00e1 la tranquilidad de saber que es seguro para su congregaci\u00f3n usar estas sillas en los a\u00f1os venideros.<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-bertolini-accordion mityinc-block\"><h3 class=\"header\">\u00bfQu\u00e9 es una prueba de carga est\u00e1tica del marco y por qu\u00e9 es importante?<\/h3><div class=\"body\">\n<p>Durante la primera prueba de carga del armaz\u00f3n, se colocan 500 libras de concreto en las patas delanteras de una silla Bertolini est\u00e1ndar. Luego, el armaz\u00f3n de la silla se somete a una segunda prueba de carga del armaz\u00f3n en la que se colocan 1,000 libras de concreto sobre el armaz\u00f3n. Ninguna de las estructuras de las sillas Bertolini muestra fatiga durante estas pruebas, lo que demuestra que la silla puede soportar hasta 1000 libras de peso. Esto significa que su congregaci\u00f3n siempre estar\u00e1 segura al sentarse o apilar estas sillas. Repetimos frecuentemente esta y otras pruebas de durabilidad en todas las sillas Bertolini para garantizar la resistencia de los productos.<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-bertolini-accordion mityinc-block\"><h3 class=\"header\">\u00bfPor qu\u00e9 es importante comprar s\u00f3lo sillas que puedan pasar una prueba de emisiones?<\/h3><div class=\"body\">\n<p>Una silla de iglesia de fabricaci\u00f3n barata puede emitir altos niveles de formaldeh\u00eddo y otras toxinas presentes en el aire. Las sillas Bertolini cumplen con todos los requisitos de emisiones de la GSA, que son los m\u00e1s estrictos del sector. La silla Impressions tambi\u00e9n <a href=\"https:\/\/www.ul.com\/services\/ul-greenguard-certification\">Certificado Greenguard<\/a>, lo que significa que ha pasado rigurosas pruebas de emisiones qu\u00edmicas y que no contribuir\u00e1 a la contaminaci\u00f3n del aire ni a la mala calidad del aire interior.<\/p>\n<\/div><\/div>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-upholstery-amp-fabric\">Tela de tapicer\u00eda<\/h2>\n\n\n\n<div class=\"wp-block-bertolini-accordion mityinc-block\"><h3 class=\"header\">\u00bfQu\u00e9 tipo de tela se utiliza en las sillas de iglesia Bertolini?<\/h3><div class=\"body\">\n<p>Bertolini utiliza telas comerciales de alta calidad para todas las sillas de iglesia. Las f\u00e1bricas de las que adquirimos las telas cuentan con algunos de los procedimientos de control de calidad m\u00e1s estrictos que existen actualmente. La tela que utilizamos se somete a pruebas de abrasi\u00f3n de doble fricci\u00f3n para garantizar su durabilidad.<\/p>\n\n\n\n<p>Los negocios con gran afluencia de p\u00fablico, como los hoteles, someten a sus sillas a un uso intensivo y utilizan telas que se someten a pruebas de resistencia a la abrasi\u00f3n de entre 15\u00a0000 y 30\u00a0000 ciclos. Las telas est\u00e1ndar utilizadas en las sillas de iglesia Bertolini se someten a pruebas de resistencia a la abrasi\u00f3n de entre 50\u00a0000 y 250\u00a0000 ciclos sin mostrar signos de desgaste. Estas telas tambi\u00e9n se someten a pruebas de solidez del color tras la exposici\u00f3n a la luz.<\/p>\n\n\n\n<p>La silla Impressions est\u00e1 disponible en m\u00e1s de 600 telas, todas ellas seleccionadas por su est\u00e9tica, comodidad y durabilidad. La silla Essentials Church est\u00e1 fabricada con una tela resistente de poliolefina 100% en color Fossil (gris\/negro).<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-bertolini-accordion mityinc-block\"><h3 class=\"header\">\u00bfQu\u00e9 hace que la espuma utilizada en las sillas Bertolini sea tan especial?<\/h3><div class=\"body\">\n<p>Los asientos de espuma Bertolini superan en durabilidad a cualquier otro en el mercado y brindan a\u00f1os de comodidad. Las sillas para iglesias Bertolini est\u00e1n fabricadas con espuma de alta resistencia. La silla Impressions, fabricada en EE. UU., cuenta con un asiento de espuma moldeada a medida, extra suave, que ofrece comodidad a largo plazo. La espuma no contiene TDI, lo que reduce las emisiones de COV y contribuye a una mejor calidad del aire. El asiento de espuma Impressions se ajusta sobre una base de pl\u00e1stico moldeado que se adapta a la forma del cuerpo para una experiencia de asiento sumamente c\u00f3moda. Las sillas Essentials V2 incluyen un coj\u00edn de espuma de 10 cm de profundidad, lo que proporciona una gran comodidad.<\/p>\n<\/div><\/div>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-international-orders\">Pedidos Internacionales<\/h2>\n\n\n\n<div class=\"wp-block-bertolini-accordion mityinc-block\"><h3 class=\"header\">\u00bfBertolini realiza env\u00edos internacionales?<\/h3><div class=\"body\">\n<p>\u00a1S\u00ed! Bertolini puede realizar env\u00edos a pr\u00e1cticamente cualquier direcci\u00f3n del mundo. Sin embargo, tenemos instrucciones y requisitos espec\u00edficos para completar una venta internacional.<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-bertolini-accordion mityinc-block\"><h3 class=\"header\">\u00bfC\u00f3mo env\u00eda Bertolini los productos a nivel internacional?<\/h3><div class=\"body\">\n<p>Todos los env\u00edos internacionales de Bertolini se realizan mediante contenedor. El cliente es responsable de organizar el servicio de env\u00edo. Podemos sugerir servicios de env\u00edo que consideramos confiables.<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-bertolini-accordion mityinc-block\"><h3 class=\"header\">\u00bfQu\u00e9 clasifica mi pedido como internacional?<\/h3><div class=\"body\">\n<p>Cualquier pedido que se origine en una ubicaci\u00f3n fuera de los 50 estados de EE. UU. se clasifica como pedido internacional y estos pedidos est\u00e1n sujetos a pol\u00edticas de pedidos internacionales.<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-bertolini-accordion mityinc-block\"><h3 class=\"header\">\u00bfQu\u00e9 tipo de moneda se acepta en Bertolini?<\/h3><div class=\"body\">\n<p>Todos los precios se muestran en d\u00f3lares estadounidenses y esa es la \u00fanica moneda que aceptamos.<\/p>\n<\/div><\/div>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-warranty\">Garant\u00eda<\/h2>\n\n\n\n<div class=\"wp-block-bertolini-accordion mityinc-block\"><h3 class=\"header\">\u00bfQu\u00e9 durabilidad tienen las sillas de iglesia Bertolini?<\/h3><div class=\"body\">\n<p>Las sillas Bertolini le durar\u00e1n m\u00e1s de 20 a\u00f1os. Est\u00e1n dise\u00f1adas para resistir el desgaste propio del uso intensivo y mantenerse en perfecto estado sin necesidad de mantenimiento. Las sillas Bertolini Impressions tienen una garant\u00eda de 25 a\u00f1os en la espuma y la estructura, mientras que el modelo Essentials V2, de menor precio, cuenta con una garant\u00eda de 5 a\u00f1os. Las garant\u00edas de la tapicer\u00eda var\u00edan seg\u00fan la tela elegida y la garant\u00eda del fabricante textil. Ofrecemos asientos y respaldos reemplazables para prolongar a\u00fan m\u00e1s la vida \u00fatil de nuestros productos.<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-bertolini-accordion mityinc-block\"><h3 class=\"header\">\u00bfBertolini ofrece garant\u00eda en cada silla?<\/h3><div class=\"body\">\n<p>\u00a1S\u00ed! Bertolini ofrece una garant\u00eda integral y sin complicaciones en todas sus sillas, y podemos hacerlo porque sabemos que nuestros productos son los mejores. Los periodos de garant\u00eda var\u00edan seg\u00fan el modelo y los componentes de la silla. La silla Bertolini Impressions tiene una garant\u00eda de 25 a\u00f1os, mientras que la silla Essentials, de menor precio, tiene una garant\u00eda de 5 a\u00f1os. Priorizamos las relaciones a largo plazo con nuestros clientes, por lo que nos esforzamos por garantizar que reciban las mejores sillas para iglesias que cualquier empresa pueda fabricar. Para obtener m\u00e1s informaci\u00f3n sobre la garant\u00eda, visite: <a href=\"https:\/\/bertolinidirect.com\/es\/warranty\/\">bertolinidirect.com\/garant\u00eda<\/a>.<\/p>\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Preguntas generales Construcci\u00f3n del marco Calificaciones y pruebas Tapicer\u00eda y tela Pedidos internacionales Garant\u00eda<\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"faqs.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-753","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.2 (Yoast SEO v27.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Frequently Asked Questions | Bertolini<\/title>\n<meta name=\"description\" content=\"Questions about the manufacturing process of your church chairs, shipping, buying international and more? Our Frequently Asked Questions has the answers.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/bertolinidirect.com\/es\/faqs\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Frequently Asked Questions\" \/>\n<meta property=\"og:description\" content=\"Questions about the manufacturing process of your church chairs, shipping, buying international and more? Our Frequently Asked Questions has the answers.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/bertolinidirect.com\/es\/faqs\/\" \/>\n<meta property=\"og:site_name\" content=\"Bertolini Direct\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-29T15:29:31+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/bertolinidirect.com\\\/es\\\/faqs\",\"url\":\"https:\\\/\\\/bertolinidirect.com\\\/es\\\/faqs\",\"name\":\"Frequently Asked Questions | Bertolini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bertolinidirect.com\\\/es\\\/#website\"},\"datePublished\":\"2024-04-19T18:33:50+00:00\",\"dateModified\":\"2026-01-29T15:29:31+00:00\",\"description\":\"Questions about the manufacturing process of your church chairs, shipping, buying international and more? Our Frequently Asked Questions has the answers.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/bertolinidirect.com\\\/es\\\/faqs#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/bertolinidirect.com\\\/es\\\/faqs\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/bertolinidirect.com\\\/es\\\/faqs#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/bertolinidirect.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Frequently Asked Questions\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/bertolinidirect.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/bertolinidirect.com\\\/es\\\/\",\"name\":\"Bertolini\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/bertolinidirect.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Preguntas frecuentes | Bertolini","description":"\u00bfPreguntas sobre el proceso de fabricaci\u00f3n de sus sillas de iglesia, env\u00edos, compras internacionales y m\u00e1s? Nuestras Preguntas frecuentes tienen las respuestas.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/bertolinidirect.com\/es\/faqs\/","og_locale":"es_MX","og_type":"article","og_title":"Frequently Asked Questions","og_description":"Questions about the manufacturing process of your church chairs, shipping, buying international and more? Our Frequently Asked Questions has the answers.","og_url":"https:\/\/bertolinidirect.com\/es\/faqs\/","og_site_name":"Bertolini Direct","article_modified_time":"2026-01-29T15:29:31+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/bertolinidirect.com\/es\/faqs","url":"https:\/\/bertolinidirect.com\/es\/faqs","name":"Preguntas frecuentes | Bertolini","isPartOf":{"@id":"https:\/\/bertolinidirect.com\/es\/#website"},"datePublished":"2024-04-19T18:33:50+00:00","dateModified":"2026-01-29T15:29:31+00:00","description":"\u00bfPreguntas sobre el proceso de fabricaci\u00f3n de sus sillas de iglesia, env\u00edos, compras internacionales y m\u00e1s? Nuestras Preguntas frecuentes tienen las respuestas.","breadcrumb":{"@id":"https:\/\/bertolinidirect.com\/es\/faqs#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/bertolinidirect.com\/es\/faqs"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/bertolinidirect.com\/es\/faqs#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/bertolinidirect.com\/"},{"@type":"ListItem","position":2,"name":"Frequently Asked Questions"}]},{"@type":"WebSite","@id":"https:\/\/bertolinidirect.com\/es\/#website","url":"https:\/\/bertolinidirect.com\/es\/","name":"Bertolini","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/bertolinidirect.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/bertolinidirect.com\/es\/wp-json\/wp\/v2\/pages\/753","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bertolinidirect.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/bertolinidirect.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/bertolinidirect.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/bertolinidirect.com\/es\/wp-json\/wp\/v2\/comments?post=753"}],"version-history":[{"count":19,"href":"https:\/\/bertolinidirect.com\/es\/wp-json\/wp\/v2\/pages\/753\/revisions"}],"predecessor-version":[{"id":24696,"href":"https:\/\/bertolinidirect.com\/es\/wp-json\/wp\/v2\/pages\/753\/revisions\/24696"}],"wp:attachment":[{"href":"https:\/\/bertolinidirect.com\/es\/wp-json\/wp\/v2\/media?parent=753"}],"curies":[{"name":"gracias","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}